{"id":230,"date":"2016-11-17T08:39:00","date_gmt":"2016-11-17T07:39:00","guid":{"rendered":"http:\/\/www.bcsberlin.com\/whitebird\/BCSblog\/?p=230"},"modified":"2016-12-11T11:15:04","modified_gmt":"2016-12-11T10:15:04","slug":"lady-veronika-und-die-wut","status":"publish","type":"post","link":"http:\/\/www.bcsberlin.com\/whitebird\/BCSblog\/2016\/11\/17\/lady-veronika-und-die-wut\/","title":{"rendered":"Lady Veronika und die Wut"},"content":{"rendered":"<p>Von den Segelgeschichten abgesehen, \u00a0&#8211; die ich ja schon anderswo angek\u00fcndigt habe- , m\u00f6chte ich nun \u00fcber Lady Veronika schreiben.<br \/>\nVeronika ist mein 30 Jahre altes Kaj\u00fctboot, das einfach genial ist und meinem Bootspartner und mir sehr ans Herz gewachsen ist. Seit \u00fcber 10 Jahren fahren wir selbst darauf, mit Frau, mit Kindern &#8211; bei Sonne, Regen und auch mal bei K\u00e4lte. Wir heizen dann mit Yogi Tea. \ud83d\ude42<\/p>\n<figure id=\"attachment_231\" aria-describedby=\"caption-attachment-231\" style=\"width: 300px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-231 size-medium\" src=\"http:\/\/www.bcsberlin.com\/whitebird\/BCSblog\/wp-content\/uploads\/2016\/11\/P7060017-300x225.jpg\" alt=\"MyBoat\" width=\"300\" height=\"225\" srcset=\"http:\/\/www.bcsberlin.com\/whitebird\/BCSblog\/wp-content\/uploads\/2016\/11\/P7060017-300x225.jpg 300w, http:\/\/www.bcsberlin.com\/whitebird\/BCSblog\/wp-content\/uploads\/2016\/11\/P7060017-768x576.jpg 768w, http:\/\/www.bcsberlin.com\/whitebird\/BCSblog\/wp-content\/uploads\/2016\/11\/P7060017-1024x768.jpg 1024w, http:\/\/www.bcsberlin.com\/whitebird\/BCSblog\/wp-content\/uploads\/2016\/11\/P7060017-100x75.jpg 100w, http:\/\/www.bcsberlin.com\/whitebird\/BCSblog\/wp-content\/uploads\/2016\/11\/P7060017.jpg 1600w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><figcaption id=\"caption-attachment-231\" class=\"wp-caption-text\">Veronika<\/figcaption><\/figure>\n<p style=\"text-align: left;\">Hier sieht man Veronika mit Motor aufgebockt f\u00fcr die Wintersaison. Alle helfen mit bei Reparaturen.<\/p>\n<p style=\"text-align: left;\">Die Sommer-Marina liegt im Westen der Stadt. Sowohl im Sp\u00e4therbst als auch im Fr\u00fchjahr steht dann eine Transferfahrt durch den Teltowkanal mit seinen 38 km an. (siehe <a href=\"http:\/\/www.bcsberlin.com\/whitebird\/BCSblog\/2015\/10\/02\/merkwuerdig\/\" target=\"_blank\">Merkw\u00fcrdig<\/a>)<\/p>\n<p style=\"text-align: left;\"><strong>Binnennavigation<\/strong><\/p>\n<p style=\"text-align: left;\">Auf dem Weg ins Winterlager \u00a0bei USE in Gr\u00fcnau hab ich mal mein Boots-Navi angeschaltet, welches ich vom Segeln her auf meinem Tablet habe ;(Navionics) mit Karten f\u00fcr Berlin und Umland.<\/p>\n<p style=\"text-align: left;\">Nat\u00fcrlich gibt es da keine gro\u00dfen Navigationsprobleme aber ich wollte es mal probieren.\u00a0Wir fahren immer im November und Wolfram wollte mal nen hei\u00dfen Tee unter Deck bereiten. Er fragt, wo sind wir denn jetzt und wie hei\u00dft denn diese Br\u00fccke.<\/p>\n<p style=\"text-align: left;\">Ich schaue also auf das Tablet &#8211; 10 Sekunden zu lange &#8211; ja &#8211; Veronika ist ein st\u00f6rrisches Weib und l\u00e4uft aus dem Ruder und wir touchieren die Kanalwand. Untergangsgef\u00fchle und Panik kommen auf. Mein Partner versch\u00fcttet den Tee, das Man\u00f6ver des letzten Augenblicks greift nicht so richtig. Schiff b\u00e4umt sich auf, rammt die Gummileiste des Freibords in die Spundwand.<\/p>\n<p style=\"text-align: left;\">Aber wir gehen nicht unter.<\/p>\n<p style=\"text-align: left;\">Zum Gl\u00fcck ist da Loch weit oberhalb der Wasserlinie und wir k\u00f6nnen weiterfahren. Ja so ein Drama verbindet nat\u00fcrlich&#8230;..<\/p>\n<p style=\"text-align: left;\"><strong>W-u-t<\/strong><\/p>\n<p style=\"text-align: left;\">Vorige Woche stand dann Veronika aufgebockt an Land. Plane dr\u00fcber und der Winter kann kommen. In der daruffolgenden Nacht haben dann schn\u00f6de und gemeine Diebe den Au\u00dfenbordmotor geklaut, gestohlen, entwendet. Nichts ist versichert. USE, der Winterlagerbetreiber sagt, dass ist hier nur ein Parkplatz, wir haben aber auch keine Kasko, sondern nur Haftpflicht.<\/p>\n<p style=\"text-align: left;\">Was nun? Verschrotten, versenken oder was? Ein Trost &#8211; die Diebe haben gleich zwei Familien gesch\u00e4digt &#8211; und kommen NICHT in den Himmel!<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Von den Segelgeschichten abgesehen, \u00a0&#8211; die ich ja schon anderswo angek\u00fcndigt habe- , m\u00f6chte ich nun \u00fcber Lady Veronika schreiben. Veronika ist mein 30 Jahre altes Kaj\u00fctboot, das einfach genial ist und meinem Bootspartner und mir sehr ans Herz gewachsen ist. Seit \u00fcber 10 Jahren fahren wir selbst darauf, mit Frau, mit Kindern &#8211; bei &hellip; <\/p>\n<p class=\"link-more\"><a href=\"http:\/\/www.bcsberlin.com\/whitebird\/BCSblog\/2016\/11\/17\/lady-veronika-und-die-wut\/\" class=\"more-link\"><span class=\"screen-reader-text\">\u201eLady Veronika und die Wut\u201c<\/span> weiterlesen<\/a><\/p>\n","protected":false},"author":1,"featured_media":124,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[37],"tags":[33,31,32,38,39],"class_list":["post-230","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-watersports","tag-aussenboarder","tag-boating","tag-boot","tag-diebstahl","tag-motorboot"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v15.6.2 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Lady Veronika und die Wut - BCSberlin.de<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"http:\/\/www.bcsberlin.com\/whitebird\/BCSblog\/2016\/11\/17\/lady-veronika-und-die-wut\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Lady Veronika und die Wut - BCSberlin.de\" \/>\n<meta property=\"og:description\" content=\"Von den Segelgeschichten abgesehen, \u00a0&#8211; die ich ja schon anderswo angek\u00fcndigt habe- , m\u00f6chte ich nun \u00fcber Lady Veronika schreiben. Veronika ist mein 30 Jahre altes Kaj\u00fctboot, das einfach genial ist und meinem Bootspartner und mir sehr ans Herz gewachsen ist. Seit \u00fcber 10 Jahren fahren wir selbst darauf, mit Frau, mit Kindern &#8211; bei &hellip; \u201eLady Veronika und die Wut\u201c weiterlesen\" \/>\n<meta property=\"og:url\" content=\"http:\/\/www.bcsberlin.com\/whitebird\/BCSblog\/2016\/11\/17\/lady-veronika-und-die-wut\/\" \/>\n<meta property=\"og:site_name\" content=\"BCSberlin.de\" \/>\n<meta property=\"article:published_time\" content=\"2016-11-17T07:39:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2016-12-11T10:15:04+00:00\" \/>\n<meta property=\"og:image\" content=\"http:\/\/www.bcsberlin.com\/whitebird\/BCSblog\/wp-content\/uploads\/2016\/10\/cropped-2012-11-nikon-zuhause-und-malediven-061-2.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"980\" \/>\n\t<meta property=\"og:image:height\" content=\"155\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Gesch\u00e4tzte Lesezeit\">\n\t<meta name=\"twitter:data1\" content=\"2\u00a0Minuten\">\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebSite\",\"@id\":\"http:\/\/www.bcsberlin.com\/whitebird\/BCSblog\/#website\",\"url\":\"http:\/\/www.bcsberlin.com\/whitebird\/BCSblog\/\",\"name\":\"BCSberlin.de\",\"description\":\"Beratung Computer Software Seit 20 Jahre Erfahrung von Microprozessor bis IBM Mainframe\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":\"http:\/\/www.bcsberlin.com\/whitebird\/BCSblog\/?s={search_term_string}\",\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"de\"},{\"@type\":\"ImageObject\",\"@id\":\"http:\/\/www.bcsberlin.com\/whitebird\/BCSblog\/2016\/11\/17\/lady-veronika-und-die-wut\/#primaryimage\",\"inLanguage\":\"de\",\"url\":\"http:\/\/www.bcsberlin.com\/whitebird\/BCSblog\/wp-content\/uploads\/2016\/10\/cropped-2012-11-nikon-zuhause-und-malediven-061-2.jpg\",\"width\":980,\"height\":155,\"caption\":\"Sacrow Paaretzer Kanal\"},{\"@type\":\"WebPage\",\"@id\":\"http:\/\/www.bcsberlin.com\/whitebird\/BCSblog\/2016\/11\/17\/lady-veronika-und-die-wut\/#webpage\",\"url\":\"http:\/\/www.bcsberlin.com\/whitebird\/BCSblog\/2016\/11\/17\/lady-veronika-und-die-wut\/\",\"name\":\"Lady Veronika und die Wut - BCSberlin.de\",\"isPartOf\":{\"@id\":\"http:\/\/www.bcsberlin.com\/whitebird\/BCSblog\/#website\"},\"primaryImageOfPage\":{\"@id\":\"http:\/\/www.bcsberlin.com\/whitebird\/BCSblog\/2016\/11\/17\/lady-veronika-und-die-wut\/#primaryimage\"},\"datePublished\":\"2016-11-17T07:39:00+00:00\",\"dateModified\":\"2016-12-11T10:15:04+00:00\",\"author\":{\"@id\":\"http:\/\/www.bcsberlin.com\/whitebird\/BCSblog\/#\/schema\/person\/2177c599dcb595801896981effae710f\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"http:\/\/www.bcsberlin.com\/whitebird\/BCSblog\/2016\/11\/17\/lady-veronika-und-die-wut\/\"]}]},{\"@type\":\"Person\",\"@id\":\"http:\/\/www.bcsberlin.com\/whitebird\/BCSblog\/#\/schema\/person\/2177c599dcb595801896981effae710f\",\"name\":\"uli48\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"http:\/\/www.bcsberlin.com\/whitebird\/BCSblog\/#personlogo\",\"inLanguage\":\"de\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/09ea48a11fcd4e472c990993d9bb2ff68d8ffb5d9cb0abfc438877d8ed989715?s=96&d=mm&r=g\",\"caption\":\"uli48\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","_links":{"self":[{"href":"http:\/\/www.bcsberlin.com\/whitebird\/BCSblog\/wp-json\/wp\/v2\/posts\/230","targetHints":{"allow":["GET"]}}],"collection":[{"href":"http:\/\/www.bcsberlin.com\/whitebird\/BCSblog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/www.bcsberlin.com\/whitebird\/BCSblog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/www.bcsberlin.com\/whitebird\/BCSblog\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"http:\/\/www.bcsberlin.com\/whitebird\/BCSblog\/wp-json\/wp\/v2\/comments?post=230"}],"version-history":[{"count":4,"href":"http:\/\/www.bcsberlin.com\/whitebird\/BCSblog\/wp-json\/wp\/v2\/posts\/230\/revisions"}],"predecessor-version":[{"id":252,"href":"http:\/\/www.bcsberlin.com\/whitebird\/BCSblog\/wp-json\/wp\/v2\/posts\/230\/revisions\/252"}],"wp:featuredmedia":[{"embeddable":true,"href":"http:\/\/www.bcsberlin.com\/whitebird\/BCSblog\/wp-json\/wp\/v2\/media\/124"}],"wp:attachment":[{"href":"http:\/\/www.bcsberlin.com\/whitebird\/BCSblog\/wp-json\/wp\/v2\/media?parent=230"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/www.bcsberlin.com\/whitebird\/BCSblog\/wp-json\/wp\/v2\/categories?post=230"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/www.bcsberlin.com\/whitebird\/BCSblog\/wp-json\/wp\/v2\/tags?post=230"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}